{"id":3127,"date":"2020-12-04T16:42:52","date_gmt":"2020-12-04T08:42:52","guid":{"rendered":"https:\/\/test.huayuansh.com\/?p=3127"},"modified":"2026-08-17T08:43:46","modified_gmt":"2026-08-17T00:43:46","slug":"precios-de-obleas-de-8-pulgadas-subieron-hasta-un-40-en-2021","status":"publish","type":"post","link":"https:\/\/huayuansh.com\/es\/precios-de-obleas-de-8-pulgadas-subieron-hasta-un-40-en-2021\/","title":{"rendered":"El precio de las obleas de 8 pulgadas aumentar\u00e1 hasta 40% en 2021"},"content":{"rendered":"<p>Todas las fundiciones de semiconductores se preparan para aumentar el precio de sus obleas de 8 pulgadas a partir de 2021. Un informe de DigiTimes arroja luz sobre varias empresas de fundici\u00f3n, como UMC (United Microelectronics), Global Foundries y Vanguard International Semiconductor (VIS), que han subido sus precios de las obleas de 8 pulgadas entre 10 y 151 TTP3T en el cuarto trimestre de 2020, y otros 20 y 401 TTP3T en 2021. Las fundiciones no suelen aplicar precios fijos, sino que se basan en presupuestos espec\u00edficos en funci\u00f3n del tama\u00f1o y los requisitos de dise\u00f1o de un pedido (por parte de un dise\u00f1ador de chips sin f\u00e1brica).<\/p>\n\n\n\n<p>La industria de la fundici\u00f3n opera a grandes rasgos en nodos de fabricaci\u00f3n de silicio y tama\u00f1os de oblea. Este art\u00edculo de Telescope Magazine ofrece una visi\u00f3n de los casos de uso t\u00edpicos de cada tama\u00f1o de oblea. Aunque se refiere estrictamente a los precios de las obleas de 200 mm (8 pulgadas), puede extrapolarse una inminente subida de precios en toda la industria de semiconductores sobre la base de importantes aumentos de los costes laborales.<\/p>\n\n\n\n<p>Recientemente, muchas instituciones han visitado intensamente las empresas de semiconductores relativos para investigar y tratar de indagar sobre el aumento de precios de las empresas que cotizan en bolsa, que han recibido m\u00e1s de una ronda de investigaci\u00f3n. A nivel de las empresas que cotizan en bolsa, algunas empresas reconocen directamente el aumento de los precios, mientras que otras \"siguen ocult\u00e1ndolo en parte\" y responden indirectamente a la cuesti\u00f3n del aumento de los precios.<\/p>\n\n\n\n<p>Reporter inquiry found that a number of semiconductor relative enterprises recently released the survey records showing that the rise in prices has become one of the most frequently asked questions of institutional research.<\/p>\n\n\n\n<p>El registro de investigaci\u00f3n publicado por Li-on Microelectronics el 1 de diciembre refleja la situaci\u00f3n de la investigaci\u00f3n de la instituci\u00f3n entre el 9 y el 27 de noviembre, periodo en el que hasta 43 instituciones participaron en la investigaci\u00f3n.<\/p>\n\n\n\n<p>La empresa se centra en la investigaci\u00f3n, el desarrollo y la fabricaci\u00f3n de materiales semiconductores, chips semiconductores y productos relacionados, y ocupa una posici\u00f3n de liderazgo en la industria nacional de obleas de silicio semiconductoras y chips de diodos schottky.<\/p>\n\n\n\n<p>En la encuesta, la organizaci\u00f3n pregunt\u00f3 a la empresa: \"La empresa se encuentra actualmente en un auge de la industria relativamente alta, cuyos principales productos se espera que aumente de precio?\"<\/p>\n\n\n\n<p>A este respecto, Li-on Microelectronics dio una respuesta m\u00e1s positiva. Afirm\u00f3: \"El actual aumento de la demanda de semiconductores ha desencadenado una escasez de oferta en la cadena industrial. La escasez de capacidad de fundici\u00f3n y la subida de precios han impulsado los precios de las obleas de silicio, el embalaje y las pruebas y el dise\u00f1o de circuitos integrados. Las obleas de semiconductores y los semiconductores de la empresa, impulsados por la mejora continua del mercado de circuitos integrados, los dos negocios de dispositivos discretos cuentan actualmente con pedidos suficientes y plena capacidad de producci\u00f3n. La subida de precios de nuestros productos se ve afectada por muchos factores. En funci\u00f3n de la situaci\u00f3n actual del mercado y de la situaci\u00f3n real de nuestra empresa, algunos productos est\u00e1n negociando con los clientes la subida de precios. La decisi\u00f3n final s\u00f3lo puede tomarse tras negociar con los clientes.<\/p>\n\n\n\n<p>Al igual que Li-on Microelectronics, otra empresa de semiconductores, Jiejie Microelectronics, tambi\u00e9n respondi\u00f3 positivamente a la subida de precios en su investigaci\u00f3n.<\/p>\n\n\n\n<p>En los registros de la encuesta publicada el 30 de noviembre, para la estructura de productos de la empresa y si hay un aumento de precios en la investigaci\u00f3n, Jiejie microelectr\u00f3nica hizo una respuesta m\u00e1s detallada.<\/p>\n\n\n\n<p>Los tiristores representaron 49% de los ingresos totales de la empresa en 2019. Debido al ajuste de la estructura de productos de la empresa, se espera que representen alrededor de 40% de ingresos este a\u00f1o. Las \u00e1reas de aplicaci\u00f3n de los tiristores son principalmente el control industrial y los electrodom\u00e9sticos, as\u00ed como la electr\u00f3nica del autom\u00f3vil. El 16 de noviembre de este a\u00f1o, debido a factores como el aumento del precio de algunas materias primas, se ajustaron (subieron) los precios de los productos. Los productos relativos a MOSFET representaron 15% de los ingresos totales de la empresa en 2019 y superar\u00e1n los 20% este a\u00f1o. Las principales \u00e1reas de aplicaci\u00f3n son el control industrial y la iluminaci\u00f3n. Debido al aumento de precios de los productos relativos VD MOS y TRENCH MOS este a\u00f1o causado por las fundiciones, algunos productos se han ajustado (actualizado). SGT MOS en el futuro, principalmente la sustituci\u00f3n de importaciones, tiene una buena sostenibilidad de la rentabilidad, el precio y el margen bruto son relativamente altos. Los dispositivos de protecci\u00f3n, que representaron 20% de los ingresos totales de la compa\u00f1\u00eda en 2019, superar\u00e1n los 25% este a\u00f1o. Debido a la escalada de la guerra comercial chino-estadounidense y el impacto de la sustituci\u00f3n de importaciones para los dispositivos de protecci\u00f3n este a\u00f1o, algunos productos han realizado algunos aumentos de precios, que no son grandes, con un precio promedio de alrededor de 3%.<\/p>\n\n\n\n<p>A diferencia de las dos empresas anteriores, NCEPOWER, cuya actividad principal es la I+D, el dise\u00f1o y la venta de dispositivos semiconductores de potencia, como MOSFET e IGBT, no ha respondido positivamente a la subida de precios.<\/p>\n\n\n\n<p>NCEPOWER expresa, la empresa se ha comprometido a los clientes de aguas abajo para establecer un largo plazo las relaciones amistosas de cooperaci\u00f3n, que no ha comenzado a subir los precios en general.<\/p>\n\n\n\n<p>Sin embargo, en respuesta a las continuas preguntas de la agencia sobre los pedidos de la empresa y la prosperidad actual de la industria, NCEPOWER afirm\u00f3 que los clientes del sector descendente de la empresa se encuentran actualmente en un estado de fuerte demanda seg\u00fan sus pedidos y la comunicaci\u00f3n con los clientes. Por el momento, los pedidos en curso de la empresa est\u00e1n programados hasta 2021. El auge de la industria en esta ronda se debe a una combinaci\u00f3n de muchos factores. La empresa es relativamente optimista sobre el auge de la industria en esta ronda de acuerdo con los pedidos existentes de la empresa y la comunicaci\u00f3n con los clientes y compa\u00f1eros.<\/p>\n\n\n\n<p>Desde el punto de vista del precio de las acciones, las cotizaciones recientes de las empresas mencionadas han ido en aumento. Desde noviembre, tanto NCEPOWER como Li-on Microelectronics han aumentado alrededor de 60%, mientras que Jiejie Microelectronics tambi\u00e9n ha aumentado alrededor de 30%.<\/p>\n\n\n\n<p><strong>La oblea de 8 pulgadas subir\u00e1 40% en 2021<\/strong><\/p>\n\n\n\n<p>La capacidad de producci\u00f3n mundial de las fundiciones de obleas de 8 pulgadas est\u00e1 al rojo vivo, los fabricantes de chips hacen cola para subir los precios con el fin de acaparar capacidad, las cotizaciones del cuarto trimestre se han elevado por completo y han desencadenado una oleada de subidas de precios.<\/p>\n\n\n\n<p>La aparici\u00f3n de nuevas aplicaciones y oportunidades de negocio, junto con el advenimiento de la era 5G, el continuo crecimiento de la demanda de semiconductores y la escasa capacidad de fundici\u00f3n en la cadena de la industria causada por la escasez de suministro y el aumento de los precios es casi seguro que continuar\u00e1n hasta la segunda mitad de 2021.<\/p>\n\n\n\n<p>Seg\u00fan la cadena de suministro de semiconductores, con la excepci\u00f3n de TSMC y Samsung Electronics, otras empresas de fundici\u00f3n han subido sus precios de fundici\u00f3n de 8 pulgadas, y el aumento comenzar\u00e1 al menos 20% en 2021. Las colas de pedidos pueden llegar al 40%, y la demanda del proceso de 12 pulgadas y 28nm ha aumentado m\u00e1s de lo previsto.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que el mercado de semiconductores est\u00e1 en pleno auge. Adem\u00e1s del aumento del precio de la fundici\u00f3n, tambi\u00e9n han seguido al alza las obleas de silicio, as\u00ed como el envasado y las pruebas y el dise\u00f1o de circuitos integrados. Entre ellos, a medida que se recupera el mercado mundial del autom\u00f3vil, la demanda se fortalece gradualmente. La capacidad de producci\u00f3n de obleas de silicio de menos de 8 pulgadas, como el cristal global, tambi\u00e9n ha anunciado su plena capacidad, incluidas las de 12 pulgadas, y se espera que suban los precios al contado.<\/p>\n\n\n\n<p><strong>El precio de las obleas de 8 pulgadas es escandaloso<\/strong><\/p>\n\n\n\n<p>En cuanto a los semiconductores, a pesar de la anterior debilidad del mercado automovil\u00edstico, la demanda de productos de electr\u00f3nica de consumo terminal ha aumentado a contracorriente, y las especificaciones de los tel\u00e9fonos m\u00f3viles 5G tambi\u00e9n se han mejorado mucho. El contenido de semiconductores ha aumentado en m\u00e1s de 30% en comparaci\u00f3n con 4G. Circuitos integrados de gesti\u00f3n de energ\u00eda, MOSFET y pantallas ultrafinas El consumo de chips como los de reconocimiento de huellas dactilares, ToF, circuitos integrados de sensores y circuitos integrados de controladores ha aumentado considerablemente.<\/p>\n\n\n\n<p>Sin embargo, como muchos chips s\u00f3lo requieren procesos maduros y producci\u00f3n en masa, la capacidad de fundici\u00f3n de 8 pulgadas sigue siendo inesperadamente escasa durante la primera mitad de la crisis epid\u00e9mica y la crisis de la guerra comercial. Desde el tercer trimestre, en el mercado escasea la oferta. La fundici\u00f3n fuera de oblea elevar\u00e1 el precio.<\/p>\n\n\n\n<p>Seg\u00fan la industria de semiconductores, debido a la insuficiente capacidad de producci\u00f3n de 8 pulgadas, es dif\u00edcil ampliarla a corto plazo, y las empresas de chips han aumentado los precios para hacerse con la capacidad de producci\u00f3n, estableci\u00e9ndose as\u00ed la tendencia de aumento de precios de las fundiciones de obleas, incluidas Global Foundries (GF), UMC y World Advanced Con la afluencia de pedidos, las cotizaciones de las fundiciones en el cuarto trimestre aumentaron alrededor de 10~15%. Debido a la alta demanda y la limitada expansi\u00f3n de la capacidad de muchas f\u00e1bricas, el aumento de la fundici\u00f3n ser\u00e1 de al menos 20%. Hasta 40% en 2021.<\/p>\n\n\n\n<p>La \u00fanica excepci\u00f3n es TSMC, que combina principalmente conjuntos de procesos maduros y avanzados. Ha declarado que no subir\u00e1 el precio para perjudicar a la asociaci\u00f3n por problemas de oferta y demanda a corto plazo.<\/p>\n\n\n\n<p>Adem\u00e1s, la demanda del proceso de 28 nm de 12 pulgadas tambi\u00e9n ha superado las expectativas, con un aumento estimado de alrededor de 20%. Por ejemplo, el proceso de 28nm de TSMC cuenta con pedidos de Sony, NXP y FocalTech, Himax y otros grandes fabricantes. Recientemente, tambi\u00e9n hay pedidos de transferencia de Qualcomm y Broadcom. UMC tambi\u00e9n tiene grandes pedidos de circuitos integrados de controladores OLED coreanos.<\/p>\n\n\n\n<p>La industria de semiconductores se\u00f1al\u00f3 que, en comparaci\u00f3n con TSMC, que originalmente ten\u00eda precios de fundici\u00f3n m\u00e1s altos, UMC, que se ha retirado de la competencia de procesos avanzados, se enfrent\u00f3 en el pasado a la presi\u00f3n de la competencia de precios entre pares, por lo que las cotizaciones de la fundici\u00f3n eran bajas. Se espera que la oferta de Umc vuelva a los niveles actuales, ya que la capacidad supera a la oferta, y los m\u00e1rgenes brutos aumentar\u00e1n significativamente.<\/p>\n\n\n\n<p><strong>Dise\u00f1o de circuitos integrados, oblea de silicio con el aumento<\/strong><\/p>\n\n\n\n<p>Cabe se\u00f1alar que las empresas de dise\u00f1o de circuitos integrados tambi\u00e9n han subido sus precios debido al aumento de los costes de las fundiciones. Por ejemplo, Novatek y FocalTech ajustaron sus ofertas en funci\u00f3n de los distintos clientes y pedidos. En un principio, las obleas de silicio estaban totalmente cargadas con 12 pulgadas, y la tasa de utilizaci\u00f3n de la capacidad original de menos de 8 pulgadas era s\u00f3lo de 70%. Ahora, el mercado mundial del autom\u00f3vil se est\u00e1 recuperando. La demanda aumenta r\u00e1pidamente, y la capacidad de producci\u00f3n se acerca a la plena capacidad. Los precios al contado, incluidos los de Global Crystal y Waferwork, subir\u00e1n en 2021.<\/p>\n\n\n\n<p><strong>El sello vuelve a subir<\/strong><\/p>\n\n\n\n<p>En cuanto al envasado y las pruebas, el mercado tambi\u00e9n ha informado de que el coste de materiales como los sustratos para circuitos integrados ha subido en respuesta al aumento de las cotizaciones, y han seguido llegando pedidos de envasado. ASE y otras empresas de embalaje y pruebas han aumentado gradualmente los precios de los nuevos pedidos en 20-30% en los cuartos trimestres. A partir de principios de 2021, el precio medio de los pedidos volver\u00e1 a aumentar en torno a 5-10%.<\/p>\n\n\n\n<p>Los fabricantes de semiconductores dijeron que los recientes aumentos de precios probablemente reflejen cambios en los costes para los usuarios finales, ya que la industria de semiconductores ha experimentado una oleada de aumentos de precios por falta de existencias, que se espera que se prolongue hasta la segunda mitad de 2021, debido a la escasez de capacidad de contrataci\u00f3n de obleas de 8 pulgadas.<\/p>\n\n\n\n<p>Fuente:&nbsp;<a href=\"https:\/\/www.digitimes.com\/news\/a20201124PD200.html\" target=\"_blank\" rel=\"noreferrer noopener\">DigiTimes<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Todas las fundiciones de semiconductores se preparan para aumentar el precio de sus obleas de 8 pulgadas a partir de 2021. Un informe de DigiTimes arroja luz sobre...<\/p>","protected":false},"author":1,"featured_media":3746,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-3127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insights"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v26.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>8-inch Wafer Prices Rising by Up to 40% in 2021 | HUAYUAN<\/title>\n<meta name=\"description\" content=\"Wafer prices rising: Semiconductor foundries across the board are preparing to raise price quotes of their 8-inch wafers from 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huayuansh.com\/es\/precios-de-obleas-de-8-pulgadas-subieron-hasta-un-40-en-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8-inch Wafer Prices Rising by Up to 40% in 2021\" \/>\n<meta property=\"og:description\" content=\"Wafer prices rising: Semiconductor foundries across the board are preparing to raise price quotes of their 8-inch wafers from 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huayuansh.com\/es\/precios-de-obleas-de-8-pulgadas-subieron-hasta-un-40-en-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"HUAYUAN RFID Tag Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-04T08:42:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-17T00:43:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"HUAYUAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"HUAYUAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/\"},\"author\":{\"name\":\"HUAYUAN\",\"@id\":\"https:\/\/huayuansh.com\/#\/schema\/person\/293ddee270c9dd0957149754bd3d1f75\"},\"headline\":\"8-inch Wafer Prices Rising by Up to 40% in 2021\",\"datePublished\":\"2020-12-04T08:42:52+00:00\",\"dateModified\":\"2026-08-17T00:43:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/\"},\"wordCount\":1696,\"publisher\":{\"@id\":\"https:\/\/huayuansh.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp\",\"articleSection\":[\"Insights\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/\",\"url\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/\",\"name\":\"8-inch Wafer Prices Rising by Up to 40% in 2021 | HUAYUAN\",\"isPartOf\":{\"@id\":\"https:\/\/huayuansh.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp\",\"datePublished\":\"2020-12-04T08:42:52+00:00\",\"dateModified\":\"2026-08-17T00:43:46+00:00\",\"description\":\"Wafer prices rising: Semiconductor foundries across the board are preparing to raise price quotes of their 8-inch wafers from 2021.\",\"breadcrumb\":{\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage\",\"url\":\"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp\",\"contentUrl\":\"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huayuansh.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8-inch Wafer Prices Rising by Up to 40% in 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huayuansh.com\/#website\",\"url\":\"https:\/\/huayuansh.com\/\",\"name\":\"HUAYUAN RFID Tag Manufacturer\",\"description\":\"HUAYUAN RFID Tag Manufacturer\",\"publisher\":{\"@id\":\"https:\/\/huayuansh.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huayuansh.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/huayuansh.com\/#organization\",\"name\":\"HUAYUAN RFID Tag Manufacturer\",\"url\":\"https:\/\/huayuansh.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/huayuansh.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/huayuansh.com\/wp-content\/uploads\/2024\/09\/cropped-HUAYUAN.webp\",\"contentUrl\":\"https:\/\/huayuansh.com\/wp-content\/uploads\/2024\/09\/cropped-HUAYUAN.webp\",\"width\":895,\"height\":279,\"caption\":\"HUAYUAN RFID Tag Manufacturer\"},\"image\":{\"@id\":\"https:\/\/huayuansh.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/huayuansh.com\/#\/schema\/person\/293ddee270c9dd0957149754bd3d1f75\",\"name\":\"HUAYUAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/huayuansh.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/huayuansh.com\/wp-content\/litespeed\/avatar\/7848d81700d3c053a0af48bb39128c40.jpg?ver=1788332189\",\"contentUrl\":\"https:\/\/huayuansh.com\/wp-content\/litespeed\/avatar\/7848d81700d3c053a0af48bb39128c40.jpg?ver=1788332189\",\"caption\":\"HUAYUAN\"},\"sameAs\":[\"https:\/\/huayuansh.com\"],\"url\":\"https:\/\/huayuansh.com\/es\/author\/shyec2024\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Los precios de las obleas de 8 pulgadas aumentar\u00e1n hasta 40% en 2021 | HUAYUAN","description":"Suben los precios de las obleas: Todas las fundiciones de semiconductores se preparan para subir los precios de sus obleas de 8 pulgadas a partir de 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huayuansh.com\/es\/precios-de-obleas-de-8-pulgadas-subieron-hasta-un-40-en-2021\/","og_locale":"es_ES","og_type":"article","og_title":"8-inch Wafer Prices Rising by Up to 40% in 2021","og_description":"Wafer prices rising: Semiconductor foundries across the board are preparing to raise price quotes of their 8-inch wafers from 2021.","og_url":"https:\/\/huayuansh.com\/es\/precios-de-obleas-de-8-pulgadas-subieron-hasta-un-40-en-2021\/","og_site_name":"HUAYUAN RFID Tag Manufacturer","article_published_time":"2020-12-04T08:42:52+00:00","article_modified_time":"2026-08-17T00:43:46+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp","type":"image\/webp"}],"author":"HUAYUAN","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"HUAYUAN","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#article","isPartOf":{"@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/"},"author":{"name":"HUAYUAN","@id":"https:\/\/huayuansh.com\/#\/schema\/person\/293ddee270c9dd0957149754bd3d1f75"},"headline":"8-inch Wafer Prices Rising by Up to 40% in 2021","datePublished":"2020-12-04T08:42:52+00:00","dateModified":"2026-08-17T00:43:46+00:00","mainEntityOfPage":{"@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/"},"wordCount":1696,"publisher":{"@id":"https:\/\/huayuansh.com\/#organization"},"image":{"@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp","articleSection":["Insights"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/","url":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/","name":"Los precios de las obleas de 8 pulgadas aumentar\u00e1n hasta 40% en 2021 | HUAYUAN","isPartOf":{"@id":"https:\/\/huayuansh.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage"},"image":{"@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp","datePublished":"2020-12-04T08:42:52+00:00","dateModified":"2026-08-17T00:43:46+00:00","description":"Suben los precios de las obleas: Todas las fundiciones de semiconductores se preparan para subir los precios de sus obleas de 8 pulgadas a partir de 2021.","breadcrumb":{"@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#primaryimage","url":"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp","contentUrl":"https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021.webp","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/huayuansh.com\/8-inch-wafer-prices-rising-by-up-to-40-in-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huayuansh.com\/"},{"@type":"ListItem","position":2,"name":"8-inch Wafer Prices Rising by Up to 40% in 2021"}]},{"@type":"WebSite","@id":"https:\/\/huayuansh.com\/#website","url":"https:\/\/huayuansh.com\/","name":"Fabricante de etiquetas RFID HUAYUAN","description":"Fabricante de etiquetas RFID HUAYUAN","publisher":{"@id":"https:\/\/huayuansh.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huayuansh.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/huayuansh.com\/#organization","name":"Fabricante de etiquetas RFID HUAYUAN","url":"https:\/\/huayuansh.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/huayuansh.com\/#\/schema\/logo\/image\/","url":"https:\/\/huayuansh.com\/wp-content\/uploads\/2024\/09\/cropped-HUAYUAN.webp","contentUrl":"https:\/\/huayuansh.com\/wp-content\/uploads\/2024\/09\/cropped-HUAYUAN.webp","width":895,"height":279,"caption":"HUAYUAN RFID Tag Manufacturer"},"image":{"@id":"https:\/\/huayuansh.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/huayuansh.com\/#\/schema\/person\/293ddee270c9dd0957149754bd3d1f75","name":"HUAYUAN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/huayuansh.com\/#\/schema\/person\/image\/","url":"https:\/\/huayuansh.com\/wp-content\/litespeed\/avatar\/7848d81700d3c053a0af48bb39128c40.jpg?ver=1788332189","contentUrl":"https:\/\/huayuansh.com\/wp-content\/litespeed\/avatar\/7848d81700d3c053a0af48bb39128c40.jpg?ver=1788332189","caption":"HUAYUAN"},"sameAs":["https:\/\/huayuansh.com"],"url":"https:\/\/huayuansh.com\/es\/author\/shyec2024\/"}]}},"taxonomy_info":{"category":[{"value":40,"label":"Insights"}]},"featured_image_src_large":["https:\/\/huayuansh.com\/wp-content\/uploads\/2020\/12\/8-inch-Wafer-Prices-Rising-by-Up-to-40-in-2021-1024x576.webp",1024,576,true],"author_info":{"display_name":"HUAYUAN","author_link":"https:\/\/huayuansh.com\/es\/author\/shyec2024\/"},"comment_info":0,"category_info":[{"term_id":40,"name":"Insights","slug":"insights","term_group":0,"term_taxonomy_id":40,"taxonomy":"category","description":"","parent":0,"count":6,"filter":"raw","cat_ID":40,"category_count":6,"category_description":"","cat_name":"Insights","category_nicename":"insights","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/posts\/3127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/comments?post=3127"}],"version-history":[{"count":1,"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/posts\/3127\/revisions"}],"predecessor-version":[{"id":3129,"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/posts\/3127\/revisions\/3129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/media\/3746"}],"wp:attachment":[{"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/media?parent=3127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/categories?post=3127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/huayuansh.com\/es\/wp-json\/wp\/v2\/tags?post=3127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}